{"id":10954,"date":"2024-05-04T01:52:08","date_gmt":"2024-05-03T23:52:08","guid":{"rendered":"https:\/\/termedimonticelli.it\/wellness-packages\/wochenmitte-spezial-2\/"},"modified":"2026-04-04T09:17:57","modified_gmt":"2026-04-04T07:17:57","slug":"wochenmitte-spezial-2","status":"publish","type":"wellness-packages","link":"https:\/\/termedimonticelli.it\/de\/pacchetti-benessere\/wochenmitte-spezial-2\/","title":{"rendered":"Wochenmitte Spezial"},"content":{"rendered":"<p>Unser interessantestes Angebot an den weniger frequentierten Tagen der Woche, das allen G\u00e4sten gewidmet ist, die sich gerne in aller Ruhe von den warmen Thermalwassern und den D\u00e4mpfen der Saunen und t\u00fcrkischen B\u00e4der verw\u00f6hnen lassen.<br \/>\nEin ganzj\u00e4hrig g\u00fcltiges Angebot, das einen Aufenthalt von 3 N\u00e4chten mit Fr\u00fchst\u00fcck und Abendessen sowie freien Eintritt in den gesamten Wellnessbereich des Monticelli Spa beinhaltet.<br \/>\nEin einzigartiges Angebot, das das ganze Jahr \u00fcber g\u00fcltig ist und Folgendes beinhaltet:    <\/p>\n<ul>\n<li><strong>3 \u00dcbernachtungen mit Anreise am Sonntag oder Montag<\/strong>, Unterbringung im Doppel- oder Zweibettzimmer und Halbpension (Fr\u00fchst\u00fcck und Abendessen)<\/li>\n<li><strong>freier Eintritt in den gesamten Wellnessbereich des Monticelli Spa<\/strong>, von 10 bis 19 Uhr, mit vier Pools mit unterschiedlich temperiertem Thermalwasser, Saunen, t\u00fcrkischem Bad und Tepidarium, Panorama-Solarium und Fitnessraum.<\/li>\n<li><strong>24 Hektar gro\u00dfer Park<\/strong> f\u00fcr Spazierg\u00e4nge oder Fitnessaktivit\u00e4ten in Kontakt mit der Natur.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong><span class=\"font-weight-bold\">Rabatt von 10 Euro<\/span><\/strong> pro <strong>Nacht und Person<\/strong> auf die Preise f\u00fcr den gew\u00e4hlten Zeitraum. <em>Getr\u00e4nke zu den Mahlzeiten und die Kurtaxe sind nicht im Preis inbegriffen.<\/em><strong>Info und Buchung<\/strong>: Telefonisch unter <a href=\"tel:+390521658526\">0521 658526<\/a> oder per E-Mail an <a href=\"mailto:info@hoteltermemonticelli.it\">info@hoteltermemonticelli.it<\/a> mit der Frage nach dem &#8222;Mid Week&#8220; Special.<\/p>\n","protected":false},"featured_media":9488,"template":"","packages-category":[40],"packages-hotels":[44],"class_list":["post-10954","wellness-packages","type-wellness-packages","status-publish","has-post-thumbnail","hentry","packages-category-pacchetti-benessere","packages-hotels-hotel-delle-terme"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- Hotel delle Terme***<\/title>\n<meta name=\"description\" content=\"Kuraufenthalt in der Wochenmitte, 3 N\u00e4chte in einem 3-Sterne-Hotel, Ankunft Sonntag oder Montag. Ganzj\u00e4hrig g\u00fcltig, Erm\u00e4\u00dfigung \u20ac 10 pro Nacht und Person. Jetzt anfragen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/termedimonticelli.it\/de\/pacchetti-benessere\/wochenmitte-spezial-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- Hotel delle Terme***\" \/>\n<meta property=\"og:description\" content=\"Kuraufenthalt in der Wochenmitte, 3 N\u00e4chte in einem 3-Sterne-Hotel, Ankunft Sonntag oder Montag. Ganzj\u00e4hrig g\u00fcltig, Erm\u00e4\u00dfigung \u20ac 10 pro Nacht und Person. Jetzt anfragen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/termedimonticelli.it\/de\/pacchetti-benessere\/wochenmitte-spezial-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Terme di Monticelli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TermeDiMonticelli\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-04T07:17:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/termedimonticelli.it\/wp-content\/uploads\/2024\/05\/hotel-delle-terme-monticelli-terme-camera.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/termedimonticelli.it\\\/de\\\/pacchetti-benessere\\\/wochenmitte-spezial-2\\\/\",\"url\":\"https:\\\/\\\/termedimonticelli.it\\\/de\\\/pacchetti-benessere\\\/wochenmitte-spezial-2\\\/\",\"name\":\"- Hotel delle Terme***\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/termedimonticelli.it\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/termedimonticelli.it\\\/de\\\/pacchetti-benessere\\\/wochenmitte-spezial-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/termedimonticelli.it\\\/de\\\/pacchetti-benessere\\\/wochenmitte-spezial-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/termedimonticelli.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/hotel-delle-terme-monticelli-terme-camera.jpg\",\"datePublished\":\"2024-05-03T23:52:08+00:00\",\"dateModified\":\"2026-04-04T07:17:57+00:00\",\"description\":\"Kuraufenthalt in der Wochenmitte, 3 N\u00e4chte in einem 3-Sterne-Hotel, Ankunft Sonntag oder Montag. Ganzj\u00e4hrig g\u00fcltig, Erm\u00e4\u00dfigung \u20ac 10 pro Nacht und Person. Jetzt anfragen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/termedimonticelli.it\\\/de\\\/pacchetti-benessere\\\/wochenmitte-spezial-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/termedimonticelli.it\\\/de\\\/pacchetti-benessere\\\/wochenmitte-spezial-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/termedimonticelli.it\\\/de\\\/pacchetti-benessere\\\/wochenmitte-spezial-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/termedimonticelli.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/hotel-delle-terme-monticelli-terme-camera.jpg\",\"contentUrl\":\"https:\\\/\\\/termedimonticelli.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/hotel-delle-terme-monticelli-terme-camera.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/termedimonticelli.it\\\/de\\\/pacchetti-benessere\\\/wochenmitte-spezial-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/termedimonticelli.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wochenmitte Spezial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/termedimonticelli.it\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/termedimonticelli.it\\\/de\\\/\",\"name\":\"Terme di Monticelli\",\"description\":\"Terme di Monticelli\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/termedimonticelli.it\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- Hotel delle Terme***","description":"Kuraufenthalt in der Wochenmitte, 3 N\u00e4chte in einem 3-Sterne-Hotel, Ankunft Sonntag oder Montag. Ganzj\u00e4hrig g\u00fcltig, Erm\u00e4\u00dfigung \u20ac 10 pro Nacht und Person. Jetzt anfragen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/termedimonticelli.it\/de\/pacchetti-benessere\/wochenmitte-spezial-2\/","og_locale":"de_DE","og_type":"article","og_title":"- Hotel delle Terme***","og_description":"Kuraufenthalt in der Wochenmitte, 3 N\u00e4chte in einem 3-Sterne-Hotel, Ankunft Sonntag oder Montag. Ganzj\u00e4hrig g\u00fcltig, Erm\u00e4\u00dfigung \u20ac 10 pro Nacht und Person. Jetzt anfragen!","og_url":"https:\/\/termedimonticelli.it\/de\/pacchetti-benessere\/wochenmitte-spezial-2\/","og_site_name":"Terme di Monticelli","article_publisher":"https:\/\/www.facebook.com\/TermeDiMonticelli\/","article_modified_time":"2026-04-04T07:17:57+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/termedimonticelli.it\/wp-content\/uploads\/2024\/05\/hotel-delle-terme-monticelli-terme-camera.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/termedimonticelli.it\/de\/pacchetti-benessere\/wochenmitte-spezial-2\/","url":"https:\/\/termedimonticelli.it\/de\/pacchetti-benessere\/wochenmitte-spezial-2\/","name":"- Hotel delle Terme***","isPartOf":{"@id":"https:\/\/termedimonticelli.it\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/termedimonticelli.it\/de\/pacchetti-benessere\/wochenmitte-spezial-2\/#primaryimage"},"image":{"@id":"https:\/\/termedimonticelli.it\/de\/pacchetti-benessere\/wochenmitte-spezial-2\/#primaryimage"},"thumbnailUrl":"https:\/\/termedimonticelli.it\/wp-content\/uploads\/2024\/05\/hotel-delle-terme-monticelli-terme-camera.jpg","datePublished":"2024-05-03T23:52:08+00:00","dateModified":"2026-04-04T07:17:57+00:00","description":"Kuraufenthalt in der Wochenmitte, 3 N\u00e4chte in einem 3-Sterne-Hotel, Ankunft Sonntag oder Montag. Ganzj\u00e4hrig g\u00fcltig, Erm\u00e4\u00dfigung \u20ac 10 pro Nacht und Person. Jetzt anfragen!","breadcrumb":{"@id":"https:\/\/termedimonticelli.it\/de\/pacchetti-benessere\/wochenmitte-spezial-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/termedimonticelli.it\/de\/pacchetti-benessere\/wochenmitte-spezial-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/termedimonticelli.it\/de\/pacchetti-benessere\/wochenmitte-spezial-2\/#primaryimage","url":"https:\/\/termedimonticelli.it\/wp-content\/uploads\/2024\/05\/hotel-delle-terme-monticelli-terme-camera.jpg","contentUrl":"https:\/\/termedimonticelli.it\/wp-content\/uploads\/2024\/05\/hotel-delle-terme-monticelli-terme-camera.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/termedimonticelli.it\/de\/pacchetti-benessere\/wochenmitte-spezial-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/termedimonticelli.it\/"},{"@type":"ListItem","position":2,"name":"Wochenmitte Spezial"}]},{"@type":"WebSite","@id":"https:\/\/termedimonticelli.it\/de\/#website","url":"https:\/\/termedimonticelli.it\/de\/","name":"Terme di Monticelli","description":"Terme di Monticelli","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/termedimonticelli.it\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/termedimonticelli.it\/de\/wp-json\/wp\/v2\/wellness-packages\/10954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/termedimonticelli.it\/de\/wp-json\/wp\/v2\/wellness-packages"}],"about":[{"href":"https:\/\/termedimonticelli.it\/de\/wp-json\/wp\/v2\/types\/wellness-packages"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/termedimonticelli.it\/de\/wp-json\/wp\/v2\/media\/9488"}],"wp:attachment":[{"href":"https:\/\/termedimonticelli.it\/de\/wp-json\/wp\/v2\/media?parent=10954"}],"wp:term":[{"taxonomy":"packages-category","embeddable":true,"href":"https:\/\/termedimonticelli.it\/de\/wp-json\/wp\/v2\/packages-category?post=10954"},{"taxonomy":"packages-hotels","embeddable":true,"href":"https:\/\/termedimonticelli.it\/de\/wp-json\/wp\/v2\/packages-hotels?post=10954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}